{"id":2626,"date":"2024-08-28T07:53:43","date_gmt":"2024-08-28T07:53:43","guid":{"rendered":"https:\/\/wp.createlli.com\/taldea\/"},"modified":"2026-07-10T08:30:17","modified_gmt":"2026-07-10T08:30:17","slug":"taldea","status":"publish","type":"page","link":"https:\/\/createlli.com\/eu\/taldea\/","title":{"rendered":"Taldea"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"2626\" class=\"elementor elementor-2626 elementor-803\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a56c391 e-con-full e-flex e-con e-parent\" data-id=\"a56c391\" data-element_type=\"container\" id=\"next\">\n\t\t\t\t<div class=\"elementor-element elementor-element-32c431dd elementor-widget elementor-widget-heading\" data-id=\"32c431dd\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Gure taldea<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-264eb0a elementor-widget elementor-widget-heading\" data-id=\"264eb0a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Parte-hartzearen erronkei aurre egiteko aditu ezberdinen jakintza uztartzen dugu<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1d7e839 elementor-widget elementor-widget-heading\" data-id=\"1d7e839\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Anberesko bulegoa<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c0c300a e-con-full e-flex e-con e-child\" data-id=\"c0c300a\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-275deb98 e-con-full e-flex e-con e-child\" data-id=\"275deb98\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-673ab532 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"673ab532\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"#\" tabindex=\"-1\"><img fetchpriority=\"high\" decoding=\"async\" width=\"440\" height=\"440\" src=\"https:\/\/createlli.com\/wp-content\/uploads\/2024\/08\/JAN.jpg\" class=\"elementor-animation-grow attachment-full size-full wp-image-2592\" alt=\"Jan De Kezel - participation expert\" srcset=\"https:\/\/createlli.com\/wp-content\/uploads\/2024\/08\/JAN.jpg 440w, https:\/\/createlli.com\/wp-content\/uploads\/2024\/08\/JAN-300x300.jpg 300w, https:\/\/createlli.com\/wp-content\/uploads\/2024\/08\/JAN-150x150.jpg 150w\" sizes=\"(max-width: 440px) 100vw, 440px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">Jan Createlli-ren sortzailea eta bazkidea da, 30 urteko esperientziarekin. Proiektu konplexuak gidatzen ditu, bai prozesu estratega gisa, bai dinamizatzaile gisa, eta behar denean laguntza rola ere hartzen du. Bere motibazioa eragile askoren ekarpenak proiektu partekatu batean biltzea da. Hori lortu du Belgikan, Espainian, Frantzian eta Herbehereetan lurralde garapena, klima, garapen jasangarria eta mugikortasuna lantzen dituzten proiektuetan. Horrez gain, tresna digitalen garapenaren arduraduna da; haren ustez, tresna horiek funtsezkoak dira pertsona gehiagorengana iristeko eta aditu, erabakitzaile eta herritarrentzat ikusgarritasuna sortzeko. Janek nederlanderaz, ingelesez, frantsesez eta alemanez hitz egiten du.     <\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2c2f7f9a e-con-full e-flex e-con e-child\" data-id=\"2c2f7f9a\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7fb51cf4 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"7fb51cf4\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"#\" tabindex=\"-1\"><img decoding=\"async\" width=\"2320\" height=\"2320\" src=\"https:\/\/createlli.com\/wp-content\/uploads\/2024\/09\/Jan-V.jpg\" class=\"elementor-animation-grow attachment-full size-full wp-image-2638\" alt=\"Jan Vincke - participation expert\" srcset=\"https:\/\/createlli.com\/wp-content\/uploads\/2024\/09\/Jan-V.jpg 2320w, https:\/\/createlli.com\/wp-content\/uploads\/2024\/09\/Jan-V-300x300.jpg 300w, https:\/\/createlli.com\/wp-content\/uploads\/2024\/09\/Jan-V-1024x1024.jpg 1024w, https:\/\/createlli.com\/wp-content\/uploads\/2024\/09\/Jan-V-150x150.jpg 150w, https:\/\/createlli.com\/wp-content\/uploads\/2024\/09\/Jan-V-768x768.jpg 768w, https:\/\/createlli.com\/wp-content\/uploads\/2024\/09\/Jan-V-1536x1536.jpg 1536w, https:\/\/createlli.com\/wp-content\/uploads\/2024\/09\/Jan-V-2048x2048.jpg 2048w, https:\/\/createlli.com\/wp-content\/uploads\/2024\/09\/Jan-V-700x700.jpg 700w, https:\/\/createlli.com\/wp-content\/uploads\/2024\/09\/Jan-V-600x600.jpg 600w\" sizes=\"(max-width: 2320px) 100vw, 2320px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">Jan 25 urteko esperientzia duen bazkide eta prozesu dinamizatzailea da. Createllin, prozesuen esparrua ezartzen du lurralde garapena, garapen jasangarria, mugikortasuna eta (berritzailea den) eremu-garapenaren arloetan. Prozesuaren estrategia definitzen du, parte-hartze sesioak antolatzen ditu eta elkarrizketa saio txikiak zein handiak errazten ditu. Bere pasio berezia esperimentu demokratikoak eta lankidetza-modu berritzaileak diseinatzea eta gidatzea da. Kalitatezko elkarrizketa batek elkarren arteko ikaskuntza, ulermena eta irtenbide hobeak laguntzen duela uste du. Bere lanetan, jabetza partekatua sustatzen du. Janek nederlanderaz eta ingelesez hitz egiten du.      <\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-12e93eda e-con-full e-flex e-con e-child\" data-id=\"12e93eda\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-505a96a9 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"505a96a9\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"#\" tabindex=\"-1\"><img decoding=\"async\" width=\"440\" height=\"440\" src=\"https:\/\/createlli.com\/wp-content\/uploads\/2024\/08\/Guillaume-RZK.jpg\" class=\"elementor-animation-grow attachment-1536x1536 size-1536x1536 wp-image-2632\" alt=\"Guillaume - Participation consultant\" srcset=\"https:\/\/createlli.com\/wp-content\/uploads\/2024\/08\/Guillaume-RZK.jpg 440w, https:\/\/createlli.com\/wp-content\/uploads\/2024\/08\/Guillaume-RZK-300x300.jpg 300w, https:\/\/createlli.com\/wp-content\/uploads\/2024\/08\/Guillaume-RZK-150x150.jpg 150w\" sizes=\"(max-width: 440px) 100vw, 440px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">Guillaume Createlliko senior aholkularia da, komunikazioan eta parte-hartzean espezializatua. Hiri-plangintzako eta diziplina anitzeko prestakuntza du, eta nazioarteko esperientzia zabala lortu du lurralde-garapenerako estrategia, plangintza operatiboa, proiektu-kudeaketa eta proiektuaren jarraipena bezalako arloetan. Hiri-garapenaren ikuspegi zeharkakoak aukera ematen dio proiektuaren fase eta maila guztietan erronkak modu integratuan kokatzen dituzten ereduak proposatzeko. Gainera, komunikazio bisuala, parte-hartze prozesuak eta prozesu-laguntza eskaintzen ditu konferentzietan, prestakuntza-programetan eta garapen jasangarriko ekimenetan. Guillaumek frantsesa, ingelesa eta lituaniera hitz egiten ditu.    <\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-193e569 e-con-full e-flex e-con e-child\" data-id=\"193e569\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0fb1484 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"0fb1484\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"#\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"440\" height=\"440\" src=\"https:\/\/createlli.com\/wp-content\/uploads\/2024\/08\/Fabio-1.jpg\" class=\"elementor-animation-grow attachment-full size-full wp-image-2634\" alt=\"Fabio Morales - participation consultant\" srcset=\"https:\/\/createlli.com\/wp-content\/uploads\/2024\/08\/Fabio-1.jpg 440w, https:\/\/createlli.com\/wp-content\/uploads\/2024\/08\/Fabio-1-300x300.jpg 300w, https:\/\/createlli.com\/wp-content\/uploads\/2024\/08\/Fabio-1-150x150.jpg 150w\" sizes=\"(max-width: 440px) 100vw, 440px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">Fabiok berrikuntzaren kudeaketan, diseinuaren pentsamenduan, zerbitzuen diseinuan eta bistaratze tekniketan esperientzia dakar. Bere esperientziak parte-hartze, arazoak konpontzeko eta sormen lanetarako beharrezkoak diren pentsamolde eta tresnekin hornitzen ditu. Azken hiru urteetan, proiektu-kudeaketan eta elkar sorkuntzan sakondu du, eragile askorekin elkarlanean eta talde ahulen inklusioan arreta berezia jarriz. Bere zereginean, Belgikako partaidetza-proiektuetarako ekoizpena eta landa ikerketak gainbegiratzen ditu eta interesdunen kudeaketa-ekimenak onartzen ditu. Gainera, Fabiok gure parte-hartze tresna-kutxan laguntzen du, konpromiso eraginkorra izateko gure baliabideak hobetuz. Holandera eta ingelesa menperatzen ditu.     <\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-32c4d6d e-con-full e-flex e-con e-child\" data-id=\"32c4d6d\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-d986ef1 e-con-full e-flex e-con e-child\" data-id=\"d986ef1\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c9638bf elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"c9638bf\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"#\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/createlli.com\/wp-content\/uploads\/2024\/08\/Fien-Joos-ZW.jpeg\" class=\"elementor-animation-grow attachment-full size-full wp-image-2600\" alt=\"\" srcset=\"https:\/\/createlli.com\/wp-content\/uploads\/2024\/08\/Fien-Joos-ZW.jpeg 800w, https:\/\/createlli.com\/wp-content\/uploads\/2024\/08\/Fien-Joos-ZW-300x300.jpeg 300w, https:\/\/createlli.com\/wp-content\/uploads\/2024\/08\/Fien-Joos-ZW-150x150.jpeg 150w, https:\/\/createlli.com\/wp-content\/uploads\/2024\/08\/Fien-Joos-ZW-768x768.jpeg 768w, https:\/\/createlli.com\/wp-content\/uploads\/2024\/08\/Fien-Joos-ZW-600x600.jpeg 600w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">Fien trebea da diseinu grafikoan, UX diseinuan eta zerbitzu eta espazio publikoen diseinuan. Estrategian eta Interakzio Diseinuan espezializatutako Produktuen Garapenean Masterrean, berrikuntza, sormena eta iraunkortasunari buruzko arreta jartzen du proiektu guztietan. Espazio publikoen etorkizunarekin liluratuta, Fienek parte-hartzeak eta elkar sorkuntzak ezinbesteko eginkizuna duela uste du ingurune horiek moldatzeko. Espazio garapenari, klimari eta mugikortasunari buruzko proiektuetan laguntzen du, bisualizazioak sortzen, web diseinuan eta parte hartzeko uneetarako eta inkesta digitaletarako laguntza eskainiz. Gainera, Fienek gure sare sozialen kanalak kudeatzen ditu eta webgunearen eguneraketak gainbegiratzen ditu. Holandera eta ingelesa menperatzen ditu.     <\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-fb723f8 e-con-full e-flex e-con e-child\" data-id=\"fb723f8\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9930d80 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"9930d80\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"#\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1827\" height=\"1827\" src=\"https:\/\/createlli.com\/wp-content\/uploads\/2025\/09\/Luna.jpg\" class=\"elementor-animation-grow attachment-full size-full wp-image-6498\" alt=\"\" srcset=\"https:\/\/createlli.com\/wp-content\/uploads\/2025\/09\/Luna.jpg 1827w, https:\/\/createlli.com\/wp-content\/uploads\/2025\/09\/Luna-300x300.jpg 300w, https:\/\/createlli.com\/wp-content\/uploads\/2025\/09\/Luna-1024x1024.jpg 1024w, https:\/\/createlli.com\/wp-content\/uploads\/2025\/09\/Luna-150x150.jpg 150w, https:\/\/createlli.com\/wp-content\/uploads\/2025\/09\/Luna-768x768.jpg 768w, https:\/\/createlli.com\/wp-content\/uploads\/2025\/09\/Luna-1536x1536.jpg 1536w, https:\/\/createlli.com\/wp-content\/uploads\/2025\/09\/Luna-700x700.jpg 700w, https:\/\/createlli.com\/wp-content\/uploads\/2025\/09\/Luna-600x600.jpg 600w\" sizes=\"(max-width: 1827px) 100vw, 1827px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">Luna, soziologo eta hiri-antolatzaile gisa, arreta berezia jartzen die gai sozio-espazialei. Ziur dago eragin handiena tokian tokiko mailan lor daitekeela, espazio publikoak funtsezko zeregina betez. Arlo horretan esperientzia eskuratu zuen bere tesiko ikerketaren bidez, Ganteko Brugse Poort auzoko berdeguneei buruz; udal gobernuen Ingurumen Sailari lagunduz; eta Bilbo inguruko eta bertako espazio-antolamendu eta mugikortasun proiektuetan parte-hartze prozesuak erraztuz. Ibilbide horrekin, Createlli taldean batu da proiektu-arduradun gisa, Belgikan eta Espainian gauzatzen diren proiektuetan ekarpena eginez. Luna nederlanderaz, ingelesez eta gaztelaniaz aritzen da.    <\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-73f02e8b e-con-full e-flex e-con e-child\" data-id=\"73f02e8b\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-76a94ec3 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"76a94ec3\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"#\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"440\" height=\"440\" src=\"https:\/\/createlli.com\/wp-content\/uploads\/2026\/03\/Mirte-De-Ganck-Createlli.jpg\" class=\"elementor-animation-grow attachment-full size-full wp-image-7397\" alt=\"\" srcset=\"https:\/\/createlli.com\/wp-content\/uploads\/2026\/03\/Mirte-De-Ganck-Createlli.jpg 440w, https:\/\/createlli.com\/wp-content\/uploads\/2026\/03\/Mirte-De-Ganck-Createlli-300x300.jpg 300w, https:\/\/createlli.com\/wp-content\/uploads\/2026\/03\/Mirte-De-Ganck-Createlli-150x150.jpg 150w\" sizes=\"(max-width: 440px) 100vw, 440px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">Mirtek historia eta lurralde-plangintzan du prestakuntza, eta horrek ikuspegi analitiko sendoa eta espazio-arazoen ikuspegi orokorra ikusteko trebetasuna ematen dio. Hirigintza eta Lurralde-Plangintzako masterrean, espazio-narrazio koherente eta zabalduak eraikitzen zituzten proiektuetan lan egin zuen. Ezagutza zabala du lurralde-plangintzari, mugikortasunari, jasangarritasunari eta Flandriako espazio-tresnei buruz. Flandriako Ingurumen Saileko lurralde-planifikatzaile gisa, zonifikazio-plan handietan lagundu zuen. Irakasle, koordinatzaile, curriculumaren garatzaile eta tailerren gidari gisa lehenagoko esperientziarekin, Mirtek trebetasun bigunak eta gogorrak konbinatzen ditu ingurumen-komunikazioa eta -parte-hartzea eraginkortasunez kudeatzeko. Nederlanderaz, ingelesez eta frantsesez ondo moldatzen da, eta gaztelaniaz ere hitz egiten du pixka bat.     <\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8cb44f3 e-con-full e-flex e-con e-child\" data-id=\"8cb44f3\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1e0642b elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"1e0642b\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"#\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"440\" height=\"440\" src=\"https:\/\/createlli.com\/wp-content\/uploads\/2024\/08\/iris-vande-walle.jpg\" class=\"elementor-animation-grow attachment-full size-full wp-image-2633\" alt=\"Participation consultant\" srcset=\"https:\/\/createlli.com\/wp-content\/uploads\/2024\/08\/iris-vande-walle.jpg 440w, https:\/\/createlli.com\/wp-content\/uploads\/2024\/08\/iris-vande-walle-300x300.jpg 300w, https:\/\/createlli.com\/wp-content\/uploads\/2024\/08\/iris-vande-walle-150x150.jpg 150w\" sizes=\"(max-width: 440px) 100vw, 440px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">Ingeniari zibil gisa, Irisek urte asko eman zituen elikagai eta produktu kimikoen industrietan taldeak zuzentzen eta entrenatzen. Esperientzia zabala lortu zuen talde-dinamikan, gatazken konponbidean eta talde-prozesu erronkatsuak errazten. Gaur egun, pertsonen kudeaketako trebetasun horiek aplikatzen ditu aldaketa eta parte-hartze prozesuak gidatzeko, beti emaitza esanguratsuak lortzera bideratuta.  \n\nCreatellin, Irisek hainbat proiektu kudeatzen ditu eta prozesu orokorraren gidaritzaz eta tailerraren moderazioaz arduratzen da. Argitasuna eta norabidea mantentzen ditu, talde-ingurune konplexu edo erronkatsuetan ere. \n\nCreatellin duen lanaz gain, Iris Comisol BVko zuzendari nagusia ere bada.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-85a6f87 e-con-full e-flex e-con e-child\" data-id=\"85a6f87\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-b6c98d7 e-con-full e-flex e-con e-child\" data-id=\"b6c98d7\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b8308d1 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"b8308d1\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"#\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"2560\" src=\"https:\/\/createlli.com\/wp-content\/uploads\/2026\/01\/Irene-scaled.jpg\" class=\"elementor-animation-grow attachment-full size-full wp-image-7106\" alt=\"\" srcset=\"https:\/\/createlli.com\/wp-content\/uploads\/2026\/01\/Irene-scaled.jpg 2560w, https:\/\/createlli.com\/wp-content\/uploads\/2026\/01\/Irene-300x300.jpg 300w, https:\/\/createlli.com\/wp-content\/uploads\/2026\/01\/Irene-1024x1024.jpg 1024w, https:\/\/createlli.com\/wp-content\/uploads\/2026\/01\/Irene-150x150.jpg 150w, https:\/\/createlli.com\/wp-content\/uploads\/2026\/01\/Irene-768x768.jpg 768w, https:\/\/createlli.com\/wp-content\/uploads\/2026\/01\/Irene-1536x1536.jpg 1536w, https:\/\/createlli.com\/wp-content\/uploads\/2026\/01\/Irene-2048x2048.jpg 2048w, https:\/\/createlli.com\/wp-content\/uploads\/2026\/01\/Irene-700x700.jpg 700w, https:\/\/createlli.com\/wp-content\/uploads\/2026\/01\/Irene-600x600.jpg 600w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">Irene arkitekta da eta gaur egun Hiria eta Hirigintza masterra egiten ari da, jasangarritasunean espezializatuta. Donostia da bere jaioterria, azken urteetan Bartzelonan bizi izan da eta orain Ambereseko taldera elkartu da. Bere ibilbide akademiko eta profesionala zabala eta anitza da, eta arkitektura, hirigintza, fabrikazio digitala, administrazio publikoa eta obra\u2011kudeaketa uztartzen ditu; horrek egokitzeko gaitasuna eta ingurune askotarikoetan lan egiteko ahalmena eman dio. Bere interes nagusia hiri inklusiboago eta jasangarriagoak sortzen laguntzea da. Createllin proiektu parte\u2011hartzaileetan eta inkesta digitaletan lagunduko du. Gaztelania, euskara, ingelesa eta katalana hitz egiten ditu.     <\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2b9f0c4 e-con-full e-flex e-con e-child\" data-id=\"2b9f0c4\" data-element_type=\"container\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8ef8c93 e-con-full e-flex e-con e-child\" data-id=\"8ef8c93\" data-element_type=\"container\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-abd3fdd e-con-full e-flex e-con e-child\" data-id=\"abd3fdd\" data-element_type=\"container\">\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c152874 elementor-widget elementor-widget-heading\" data-id=\"c152874\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Bilboko bulegoa<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b0c0d6a e-con-full e-flex e-con e-child\" data-id=\"b0c0d6a\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-94a78fa e-con-full e-flex e-con e-child\" data-id=\"94a78fa\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ce3991d elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"ce3991d\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"#\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"440\" height=\"440\" src=\"https:\/\/createlli.com\/wp-content\/uploads\/2024\/08\/IRATI-1.jpg\" class=\"elementor-animation-grow attachment-full size-full wp-image-2630\" alt=\"Irati Alonso - Participation expert\" srcset=\"https:\/\/createlli.com\/wp-content\/uploads\/2024\/08\/IRATI-1.jpg 440w, https:\/\/createlli.com\/wp-content\/uploads\/2024\/08\/IRATI-1-300x300.jpg 300w, https:\/\/createlli.com\/wp-content\/uploads\/2024\/08\/IRATI-1-150x150.jpg 150w\" sizes=\"(max-width: 440px) 100vw, 440px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">2016tik dabil Irati Creattelin lanean. Arkitektura masterra du (Donostia, 2016), eta Hirigintza eta Hiri antolamenduan Masterra (Bilbo, 2017). Createllira sartu aurretik Irati aholkularitza enpresa batean lan egin zuen. Azken urteotan, parte-hartze eta dinamizazio sozialeko hainbat proiektu egin ditu, hirigintzari lotutakoak batez ere. Createlli plataformarekin parte-hartze digitaleko prozesuak aplikatzeko esperientzia ere badu. Azken urteetan, talde sozial askorekin lan egin du: haurrak eta gazteak, adinekoak, tokiko eragileak eta genero-ikuspegia duten proiektuetan. Iratik euskaraz, gaztelaniaz eta ingelesez hitz egiten du.      <\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e929056 e-con-full e-flex e-con e-child\" data-id=\"e929056\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9a9acb7 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"9a9acb7\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"#\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"440\" height=\"440\" src=\"https:\/\/createlli.com\/wp-content\/uploads\/2024\/08\/Jone2-1.jpg\" class=\"elementor-animation-grow attachment-full size-full wp-image-2628\" alt=\"\" srcset=\"https:\/\/createlli.com\/wp-content\/uploads\/2024\/08\/Jone2-1.jpg 440w, https:\/\/createlli.com\/wp-content\/uploads\/2024\/08\/Jone2-1-300x300.jpg 300w, https:\/\/createlli.com\/wp-content\/uploads\/2024\/08\/Jone2-1-150x150.jpg 150w\" sizes=\"(max-width: 440px) 100vw, 440px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">Jonek Arkitekturan masterra du, Periferien, jasangarritasunaren eta hiri-bizitasunaren inguruko gradu bat, eta Paisaia Arkitekturan masterra. Gaur egun doktorego-tesia egiten ari da, hiri inklusiboa, parte-hartzea eta diseinu jasangarria ardatz hartuta. Hiri-plangintzarako, hiri-garapeneko eta gizarte-berrikuntzako parte-hartze prozesuetan espezializatua da. 20 urteko esperientzia du arkitekto gisa eta 15 urte herritarren parte-hartzean.<br \/>Azken urteetan, haurrekin eta gazteekin egindako proiektuak, ekintzailetza sustatzeko ekimenak, herritarren arteko gatazken bitartekaritza eta genero-hirigintza landu ditu. 2015etik, Createllirekin elkarlanean aritu da. Gaztelania, euskara, ingelesa eta frantsesa hitz egiten ditu.     <\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5a572c5 e-con-full e-flex e-con e-child\" data-id=\"5a572c5\" data-element_type=\"container\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ff6de3f e-con-full e-flex e-con e-child\" data-id=\"ff6de3f\" data-element_type=\"container\">\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-07a1dc5 elementor-widget elementor-widget-heading\" data-id=\"07a1dc5\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Delhiko bulegoa<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-319cebc e-con-full e-flex e-con e-child\" data-id=\"319cebc\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-b44beb0 e-con-full e-flex e-con e-child\" data-id=\"b44beb0\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c38af88 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"c38af88\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"#\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"387\" height=\"388\" src=\"https:\/\/createlli.com\/wp-content\/uploads\/2024\/09\/Ashish.jpg\" class=\"elementor-animation-grow attachment-full size-full wp-image-2555\" alt=\"Ashish Verma - Developer\" srcset=\"https:\/\/createlli.com\/wp-content\/uploads\/2024\/09\/Ashish.jpg 387w, https:\/\/createlli.com\/wp-content\/uploads\/2024\/09\/Ashish-300x300.jpg 300w, https:\/\/createlli.com\/wp-content\/uploads\/2024\/09\/Ashish-150x150.jpg 150w\" sizes=\"(max-width: 387px) 100vw, 387px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">Ashish gure Delhi-ko garapen taldeko arduraduna da. Informatikan unibertsitate-titulua du eta 9 urteko esperientzia nazioarteko (India, Txina, Myanmar eta Japonia) web aplikazioetan eta plataforma kolaboratiboen garapenean. Erronka teknikoak gustuko ditu eta sarritan irtenbide berritzaileekin eta ikuspegi ezohikoekin harritzen du. Createllin tresna eta plataforma digitalak garatzen ditu. Ingelesa, hindia eta japoniera hitz egiten ditu.     <\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bbc4eb9 e-con-full e-flex e-con e-child\" data-id=\"bbc4eb9\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-47c60c7 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"47c60c7\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"#\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"440\" height=\"440\" src=\"https:\/\/createlli.com\/wp-content\/uploads\/2024\/08\/Vishant-square-1.jpg\" class=\"elementor-animation-grow attachment-full size-full wp-image-2631\" alt=\"Vishant Verma - Developer digital participation\" srcset=\"https:\/\/createlli.com\/wp-content\/uploads\/2024\/08\/Vishant-square-1.jpg 440w, https:\/\/createlli.com\/wp-content\/uploads\/2024\/08\/Vishant-square-1-300x300.jpg 300w, https:\/\/createlli.com\/wp-content\/uploads\/2024\/08\/Vishant-square-1-150x150.jpg 150w\" sizes=\"(max-width: 440px) 100vw, 440px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">Vishant informatikan lizentziatua da eta 2016az geroztik garatzaile gisa ari da lanean gure Delhiko taldean. Gure tresna eta plataforma digitalen garapenean laguntzen du. Vishantek hindia eta ingelesa hitz egiten ditu.  <\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-603f053 e-con-full e-flex e-con e-child\" data-id=\"603f053\" data-element_type=\"container\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5c45636 e-con-full e-flex e-con e-child\" data-id=\"5c45636\" data-element_type=\"container\">\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Gure taldea Parte-hartzearen erronkei aurre egiteko aditu ezberdinen jakintza uztartzen dugu Anberesko bulegoa Jan Createlli-ren sortzailea eta bazkidea da, 30 urteko esperientziarekin. Proiektu konplexuak gidatzen ditu, bai prozesu estratega gisa, bai dinamizatzaile gisa, eta behar denean laguntza rola ere hartzen du. Bere motibazioa eragile askoren ekarpenak proiektu partekatu batean biltzea da. Hori lortu du Belgikan, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_theme","meta":{"_acf_changed":false,"ocean_post_layout":"full-width","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"on","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","ofc_meta_disable_footer_callout":"","ofc_meta_callout_button_url":"","ofc_meta_callout_button_txt":"","ofc_meta_callout_text":"","ofc_enable_fullscreen":"disable","ofc_fullscreen_speed":0,"ofc_fullscreen_nav":"enable","ofc_fullscreen_nav_pos":"right","ofc_fullscreen_nav_color":"","ofc_fullscreen_nav_tooltip_color":"","ofc_fullscreen_responsive":0,"osh_disable_topbar_sticky":"default","osh_disable_header_sticky":"default","osh_sticky_header_style":"default","osh_sticky_header_effect":"","osh_custom_sticky_logo":0,"osh_custom_retina_sticky_logo":0,"osh_custom_sticky_logo_height":0,"osh_background_color":"","osh_links_color":"","osh_links_hover_color":"","osh_links_active_color":"","osh_links_bg_color":"","osh_links_hover_bg_color":"","osh_links_active_bg_color":"","osh_menu_social_links_color":"","osh_menu_social_hover_links_color":"","footnotes":""},"class_list":["post-2626","page","type-page","status-publish","hentry","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Taldea - Createlli | Espazio publikoaren diseinurako parte-hartzea eta baterako sorkuntza<\/title>\n<meta name=\"description\" content=\"Ezagutu Createlli taldea, esperientzia desberdinak uztartzen dituena parte-hartze erronkei aurre egiteko. Ezagutu nola gure adituek herritarrak eta interesdunak inplikatzen dituzten espazio publikoak moldatzeko.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/createlli.com\/eu\/taldea\/\" \/>\n<meta property=\"og:locale\" content=\"eu_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Taldea - Createlli | Espazio publikoaren diseinurako parte-hartzea eta baterako sorkuntza\" \/>\n<meta property=\"og:description\" content=\"Ezagutu Createlli taldea, esperientzia desberdinak uztartzen dituena parte-hartze erronkei aurre egiteko. Ezagutu nola gure adituek herritarrak eta interesdunak inplikatzen dituzten espazio publikoak moldatzeko.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/createlli.com\/eu\/taldea\/\" \/>\n<meta property=\"og:site_name\" content=\"Createlli | Espazio publikoaren diseinurako parte-hartzea eta baterako sorkuntza\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-10T08:30:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/createlli.com\/wp-content\/uploads\/2024\/08\/JAN.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"440\" \/>\n\t<meta property=\"og:image:height\" content=\"440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/createlli.com\/eu\/taldea\/\",\"url\":\"https:\/\/createlli.com\/eu\/taldea\/\",\"name\":\"Taldea - Createlli | Espazio publikoaren diseinurako parte-hartzea eta baterako sorkuntza\",\"isPartOf\":{\"@id\":\"https:\/\/createlli.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/createlli.com\/eu\/taldea\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/createlli.com\/eu\/taldea\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/createlli.com\/wp-content\/uploads\/2024\/08\/JAN.jpg\",\"datePublished\":\"2024-08-28T07:53:43+00:00\",\"dateModified\":\"2026-07-10T08:30:17+00:00\",\"description\":\"Ezagutu Createlli taldea, esperientzia desberdinak uztartzen dituena parte-hartze erronkei aurre egiteko. Ezagutu nola gure adituek herritarrak eta interesdunak inplikatzen dituzten espazio publikoak moldatzeko.\",\"breadcrumb\":{\"@id\":\"https:\/\/createlli.com\/eu\/taldea\/#breadcrumb\"},\"inLanguage\":\"eu-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/createlli.com\/eu\/taldea\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"eu-ES\",\"@id\":\"https:\/\/createlli.com\/eu\/taldea\/#primaryimage\",\"url\":\"https:\/\/createlli.com\/wp-content\/uploads\/2024\/08\/JAN.jpg\",\"contentUrl\":\"https:\/\/createlli.com\/wp-content\/uploads\/2024\/08\/JAN.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/createlli.com\/eu\/taldea\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/createlli.com\/eu\/hasiera\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Taldea\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/createlli.com\/#website\",\"url\":\"https:\/\/createlli.com\/\",\"name\":\"Createlli | Espazio publikoaren diseinurako parte-hartzea eta baterako sorkuntza\",\"description\":\"Createlli sparks change through participation and co-creation, shaping society in spatial planning, mobility, climate, sustainability, and quality of life.\",\"publisher\":{\"@id\":\"https:\/\/createlli.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/createlli.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"eu-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/createlli.com\/#organization\",\"name\":\"Createlli | Espazio publikoaren diseinurako parte-hartzea eta baterako sorkuntza\",\"url\":\"https:\/\/createlli.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"eu-ES\",\"@id\":\"https:\/\/createlli.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/createlli.com\/wp-content\/uploads\/2024\/08\/cropped-Createlli-logo-white_2.png\",\"contentUrl\":\"https:\/\/createlli.com\/wp-content\/uploads\/2024\/08\/cropped-Createlli-logo-white_2.png\",\"width\":144,\"height\":31,\"caption\":\"Createlli | Espazio publikoaren diseinurako parte-hartzea eta baterako sorkuntza\"},\"image\":{\"@id\":\"https:\/\/createlli.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Taldea - Createlli | Espazio publikoaren diseinurako parte-hartzea eta baterako sorkuntza","description":"Ezagutu Createlli taldea, esperientzia desberdinak uztartzen dituena parte-hartze erronkei aurre egiteko. Ezagutu nola gure adituek herritarrak eta interesdunak inplikatzen dituzten espazio publikoak moldatzeko.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/createlli.com\/eu\/taldea\/","og_locale":"eu_ES","og_type":"article","og_title":"Taldea - Createlli | Espazio publikoaren diseinurako parte-hartzea eta baterako sorkuntza","og_description":"Ezagutu Createlli taldea, esperientzia desberdinak uztartzen dituena parte-hartze erronkei aurre egiteko. Ezagutu nola gure adituek herritarrak eta interesdunak inplikatzen dituzten espazio publikoak moldatzeko.","og_url":"https:\/\/createlli.com\/eu\/taldea\/","og_site_name":"Createlli | Espazio publikoaren diseinurako parte-hartzea eta baterako sorkuntza","article_modified_time":"2026-07-10T08:30:17+00:00","og_image":[{"width":440,"height":440,"url":"https:\/\/createlli.com\/wp-content\/uploads\/2024\/08\/JAN.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/createlli.com\/eu\/taldea\/","url":"https:\/\/createlli.com\/eu\/taldea\/","name":"Taldea - Createlli | Espazio publikoaren diseinurako parte-hartzea eta baterako sorkuntza","isPartOf":{"@id":"https:\/\/createlli.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/createlli.com\/eu\/taldea\/#primaryimage"},"image":{"@id":"https:\/\/createlli.com\/eu\/taldea\/#primaryimage"},"thumbnailUrl":"https:\/\/createlli.com\/wp-content\/uploads\/2024\/08\/JAN.jpg","datePublished":"2024-08-28T07:53:43+00:00","dateModified":"2026-07-10T08:30:17+00:00","description":"Ezagutu Createlli taldea, esperientzia desberdinak uztartzen dituena parte-hartze erronkei aurre egiteko. Ezagutu nola gure adituek herritarrak eta interesdunak inplikatzen dituzten espazio publikoak moldatzeko.","breadcrumb":{"@id":"https:\/\/createlli.com\/eu\/taldea\/#breadcrumb"},"inLanguage":"eu-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/createlli.com\/eu\/taldea\/"]}]},{"@type":"ImageObject","inLanguage":"eu-ES","@id":"https:\/\/createlli.com\/eu\/taldea\/#primaryimage","url":"https:\/\/createlli.com\/wp-content\/uploads\/2024\/08\/JAN.jpg","contentUrl":"https:\/\/createlli.com\/wp-content\/uploads\/2024\/08\/JAN.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/createlli.com\/eu\/taldea\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/createlli.com\/eu\/hasiera\/"},{"@type":"ListItem","position":2,"name":"Taldea"}]},{"@type":"WebSite","@id":"https:\/\/createlli.com\/#website","url":"https:\/\/createlli.com\/","name":"Createlli | Espazio publikoaren diseinurako parte-hartzea eta baterako sorkuntza","description":"Createlli sparks change through participation and co-creation, shaping society in spatial planning, mobility, climate, sustainability, and quality of life.","publisher":{"@id":"https:\/\/createlli.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/createlli.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"eu-ES"},{"@type":"Organization","@id":"https:\/\/createlli.com\/#organization","name":"Createlli | Espazio publikoaren diseinurako parte-hartzea eta baterako sorkuntza","url":"https:\/\/createlli.com\/","logo":{"@type":"ImageObject","inLanguage":"eu-ES","@id":"https:\/\/createlli.com\/#\/schema\/logo\/image\/","url":"https:\/\/createlli.com\/wp-content\/uploads\/2024\/08\/cropped-Createlli-logo-white_2.png","contentUrl":"https:\/\/createlli.com\/wp-content\/uploads\/2024\/08\/cropped-Createlli-logo-white_2.png","width":144,"height":31,"caption":"Createlli | Espazio publikoaren diseinurako parte-hartzea eta baterako sorkuntza"},"image":{"@id":"https:\/\/createlli.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/createlli.com\/eu\/wp-json\/wp\/v2\/pages\/2626","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/createlli.com\/eu\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/createlli.com\/eu\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/createlli.com\/eu\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/createlli.com\/eu\/wp-json\/wp\/v2\/comments?post=2626"}],"version-history":[{"count":22,"href":"https:\/\/createlli.com\/eu\/wp-json\/wp\/v2\/pages\/2626\/revisions"}],"predecessor-version":[{"id":7592,"href":"https:\/\/createlli.com\/eu\/wp-json\/wp\/v2\/pages\/2626\/revisions\/7592"}],"wp:attachment":[{"href":"https:\/\/createlli.com\/eu\/wp-json\/wp\/v2\/media?parent=2626"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}